{"id":8727,"date":"2023-10-08T07:09:13","date_gmt":"2023-10-08T07:09:13","guid":{"rendered":"https:\/\/royalgulfrestaurant.com\/?page_id=8727"},"modified":"2025-06-17T23:47:50","modified_gmt":"2025-06-17T19:47:50","slug":"our-menu_ar","status":"publish","type":"page","link":"https:\/\/royalgulfrestaurant.com\/al_rai\/ar\/our-menu_ar\/","title":{"rendered":"Our Menu_ar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8727\" class=\"elementor elementor-8727\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72aa6c0 pt-section-content-fullwidth pt-parallax-on-scroll pt_scroll_y_180 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"72aa6c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-pt-parallax-y=\"180\" style=\"background-image: none;\" data-pt-background-image=\"https:\/\/royalgulfrestaurant.com\/wp-content\/uploads\/2023\/09\/Banner-new.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b6bc49\" data-id=\"8b6bc49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20df520 elementor-widget elementor-widget-pt_title\" data-id=\"20df520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-center\">\t            <h1 class=\"pt-title\">\n\t                \u0642\u0627\u0626\u0645\u062a\u0646\u0627\t            <\/h1>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf24676 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"cf24676\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-249e164\" data-id=\"249e164\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4630e8b elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4630e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-704acd9 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"704acd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27f3811 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"27f3811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9afcc37 elementor-widget elementor-widget-pt_title\" data-id=\"9afcc37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-center\">\t            <div class=\"pt-title-text\">\n\t                <p>\u0627\u0643\u062a\u0634\u0641 \u0645\u0637\u0628\u062e\u0646\u0627<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e45d96 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3e45d96\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-f61fe44 pt-animation-medium-offset elementor-invisible\" data-id=\"f61fe44\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f8aae1 elementor-widget elementor-widget-image\" data-id=\"0f8aae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/breakfast_ar\/#breakfast\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7281\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Breakfast-1.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29dfe4b elementor-widget elementor-widget-heading\" data-id=\"29dfe4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/breakfast_ar\/#breakfast\">\u0625\u0641\u0637\u0627\u0631\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-801d0f4 pt-animation-medium-offset elementor-invisible\" data-id=\"801d0f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2344831 elementor-widget elementor-widget-image\" data-id=\"2344831\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/sandwich_ar\/#sandwich\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7283\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Sanwiches.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a87c981 elementor-widget elementor-widget-heading\" data-id=\"a87c981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/sandwich_ar\/#sandwich\"> \u0633\u0646\u062f\u0648\u064a\u0634\u0627\u062a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1b7ad92 pt-animation-medium-offset elementor-invisible\" data-id=\"1b7ad92\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2420ad2 elementor-widget elementor-widget-image\" data-id=\"2420ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/soup_ar\/#soup\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9045\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Soups.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6226e6b elementor-widget elementor-widget-heading\" data-id=\"6226e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/soup_ar\/#soup\">\u0627\u0644\u0634\u0648\u0631\u0628\u0629<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-cdb2af1 pt-animation-medium-offset elementor-invisible\" data-id=\"cdb2af1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aecfd40 elementor-widget elementor-widget-image\" data-id=\"aecfd40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/salad_ar\/#salad\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9044\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Salads.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d35ddf elementor-widget elementor-widget-heading\" data-id=\"9d35ddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/salad_ar\/#salad\">\u0633\u0644\u0637\u0629<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e777bfa pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"e777bfa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1f8431 elementor-widget elementor-widget-image\" data-id=\"f1f8431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/appetizers_ar\/#appetizer\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7274\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93e53d0 elementor-widget elementor-widget-heading\" data-id=\"93e53d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/appetizers_ar\/#appetizer\">\u0645\u0642\u0628\u0644\u0627\u062a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-9c3933f pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"9c3933f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f60d6a elementor-widget elementor-widget-image\" data-id=\"5f60d6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/chineese_ar\/#chinese\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-8917\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Chinees.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b59744e elementor-widget elementor-widget-heading\" data-id=\"b59744e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/chineese_ar\/#chinese\">\u0635\u064a\u0646\u0649\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ad6d30 elementor-hidden-desktop elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9ad6d30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cbce77f pt-animation-medium-offset elementor-invisible\" data-id=\"cbce77f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13dd768 elementor-widget elementor-widget-image\" data-id=\"13dd768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/appetizers_ar\/#appetizer\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7274\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Appetizer.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abdb8ce elementor-widget elementor-widget-heading\" data-id=\"abdb8ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/appetizers_ar\/#appetizer\">\u0645\u0642\u0628\u0644\u0627\u062a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8cda1e6 pt-animation-medium-offset elementor-invisible\" data-id=\"8cda1e6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e0102 elementor-widget elementor-widget-image\" data-id=\"36e0102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/chineese_ar\/#chinese\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7285\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Chinees-1.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de016ec elementor-widget elementor-widget-heading\" data-id=\"de016ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/chineese_ar\/#chinese\">\u0635\u064a\u0646\u0649\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a74e0c pt-animation-medium-offset elementor-invisible\" data-id=\"8a74e0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d7eeab elementor-widget elementor-widget-image\" data-id=\"0d7eeab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/main-course_ar\/#maincourse\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9041\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b068c3 elementor-widget elementor-widget-heading\" data-id=\"9b068c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/main-course_ar\/#maincourse\">\u0627\u0644\u0637\u0628\u0642 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-31b7d34 pt-animation-medium-offset elementor-invisible\" data-id=\"31b7d34\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6921c38 elementor-widget elementor-widget-image\" data-id=\"6921c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/charcoal_ar\/#charcoal\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7286\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Charcol.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac9e15e elementor-widget elementor-widget-heading\" data-id=\"ac9e15e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/charcoal_ar\/#charcoal\">\u0641\u062d\u0645\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7d22f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d7d22f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-8e08713 pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"8e08713\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c47c473 elementor-widget elementor-widget-image\" data-id=\"c47c473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/main-course_ar\/#maincourse\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9041\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Main-Course.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4ca0b3 elementor-widget elementor-widget-heading\" data-id=\"d4ca0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/main-course_ar\/#maincourse\">\u0627\u0644\u0637\u0628\u0642 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-51cab28 pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"51cab28\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2611094 elementor-widget elementor-widget-image\" data-id=\"2611094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/charcoal_ar\/#charcoal\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9039\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Charcoal.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a385eda elementor-widget elementor-widget-heading\" data-id=\"a385eda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/charcoal_ar\/#charcoal\">\u0641\u062d\u0645\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2e64475 pt-animation-medium-offset elementor-invisible\" data-id=\"2e64475\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1530a93 elementor-widget elementor-widget-image\" data-id=\"1530a93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/tandoor_ar\/#tandoor\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7663\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/09\/tandoor-1.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-550b70d elementor-widget elementor-widget-heading\" data-id=\"550b70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/tandoor_ar\/#tandoor\">\u062a\u0646\u062f\u0648\u0631\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1b7928b pt-animation-medium-offset elementor-invisible\" data-id=\"1b7928b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7e8dd7 elementor-widget elementor-widget-image\" data-id=\"f7e8dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/curries_ar\/#curry\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-8947\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Curries.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4862474 elementor-widget elementor-widget-heading\" data-id=\"4862474\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/curries_ar\/#curry\">\u0645\u0631\u0642\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e714d0b pt-animation-medium-offset elementor-invisible\" data-id=\"e714d0b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0473155 elementor-widget elementor-widget-image\" data-id=\"0473155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/veg-paneer_ar\/#veg_paneer\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7290\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Paneer.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa283f elementor-widget elementor-widget-heading\" data-id=\"1aa283f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/veg-paneer_ar\/#veg_paneer\">\u0627\u0644\u062e\u0636\u0627\u0631 \u0648\u0627\u0644\u0628\u0627\u0646\u064a\u064a\u0631\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-fdacd9c pt-animation-medium-offset elementor-invisible\" data-id=\"fdacd9c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9b7e65 elementor-widget elementor-widget-image\" data-id=\"c9b7e65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/tandoor-bread_ar\/#tandoor\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9105\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Nan.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3807fa elementor-widget elementor-widget-heading\" data-id=\"e3807fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/tandoor-bread_ar\/#tandoor\">\u062a\u0646\u062f\u0648\u0631\u064a \u0631\u0648\u062a\u064a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ff3fda elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4ff3fda\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-c4a6f1e pt-animation-medium-offset elementor-invisible\" data-id=\"c4a6f1e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f886bae elementor-widget elementor-widget-image\" data-id=\"f886bae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/pasta_ar\/#pasta\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-8918\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Pasta.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc224f8 elementor-widget elementor-widget-heading\" data-id=\"fc224f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/pasta_ar\/#pasta\">\u0645\u0639\u0643\u0631\u0648\u0646\u0629\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-ece655d pt-animation-medium-offset elementor-invisible\" data-id=\"ece655d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4403e2a elementor-widget elementor-widget-image\" data-id=\"4403e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/fried-rice_ar\/#fried\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9040\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Fried-Rice.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d4f0b8 elementor-widget elementor-widget-heading\" data-id=\"6d4f0b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/fried-rice_ar\/#fried\">\u0623\u0631\u0632 \u0645\u0642\u0644 \n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b82da32 pt-animation-medium-offset elementor-invisible\" data-id=\"b82da32\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35de4dc elementor-widget elementor-widget-image\" data-id=\"35de4dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/noodles_ar\/#noodles\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9042\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Noodles.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c37b52 elementor-widget elementor-widget-heading\" data-id=\"1c37b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/noodles_ar\/#noodles\">\u0646\u0648\u062f\u0644\u0632 \n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-33860c3 pt-animation-medium-offset elementor-invisible\" data-id=\"33860c3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69cd628 elementor-widget elementor-widget-image\" data-id=\"69cd628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/rice-thali_ar\/#rice\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7296\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Thali-2.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54717bc elementor-widget elementor-widget-heading\" data-id=\"54717bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/rice-thali_ar\/#rice\"> \u0643\u0648\u0645\u0628\u0648 \u0648 \u062b\u0627\u0644\u064a  \n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-9771499 pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"9771499\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28b765d elementor-widget elementor-widget-image\" data-id=\"28b765d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/special_ar\/#special\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9050\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e46e36 elementor-widget elementor-widget-heading\" data-id=\"0e46e36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/special_ar\/#special\">\u062e\u0627\u0635\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-61855c8 pt-animation-medium-offset elementor-hidden-tablet elementor-invisible\" data-id=\"61855c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7d03f1 elementor-widget elementor-widget-image\" data-id=\"e7d03f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/desert_ar\/#desert\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9049\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a60f3a4 elementor-widget elementor-widget-heading\" data-id=\"a60f3a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/desert_ar\/#desert\"> \u0627\u0644\u0635\u062d\u0631\u0627\u0648\u064a<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-169abb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"169abb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-28fbfc4 pt-animation-medium-offset elementor-invisible\" data-id=\"28fbfc4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2690703 pt-animation-medium-offset elementor-invisible\" data-id=\"2690703\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fde3f7e elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"fde3f7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/special_ar\/#special\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9050\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Special.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d2540 elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"d8d2540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/special_ar\/#special\">\u062e\u0627\u0635<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-6f3eea9 pt-animation-medium-offset elementor-invisible\" data-id=\"6f3eea9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb0a021 elementor-widget elementor-widget-image\" data-id=\"bb0a021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/drinks_ar\/#juice\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-7030\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/07\/Juice.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddd2901 elementor-widget elementor-widget-heading\" data-id=\"ddd2901\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/drinks_ar\/#juice\">\u0645\u0634\u0631\u0648\u0628\u0627\u062a\n<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0d1292d pt-animation-medium-offset elementor-invisible\" data-id=\"0d1292d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd0df01 elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"dd0df01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/al_rai\/ar\/our-menu_ar\/desert_ar\/#desert\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"481\" src=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-370x481.jpg\" class=\"elementor-animation-float attachment-patiotime_370x9999 size-patiotime_370x9999 wp-image-9049\" alt=\"\" srcset=\"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-370x481.jpg 370w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-231x300.jpg 231w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-788x1024.jpg 788w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-768x998.jpg 768w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-780x1014.jpg 780w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-600x780.jpg 600w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-550x715.jpg 550w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-255x332.jpg 255w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g-115x150.jpg 115w, https:\/\/royalgulfrestaurant.com\/al_rai\/wp-content\/uploads\/2023\/11\/Desert-g.jpg 1000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afe920f elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"afe920f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/al_rai\/ar\/our-menu_ar\/desert_ar\/#desert\"> \u0627\u0644\u0635\u062d\u0631\u0627\u0648\u064a<\/a><\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4713d26 pt-animation-medium-offset elementor-invisible\" data-id=\"4713d26\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0642\u0627\u0626\u0645\u062a\u0646\u0627 \u0627\u0643\u062a\u0634\u0641 \u0645\u0637\u0628\u062e\u0646\u0627 \u0625\u0641\u0637\u0627\u0631 \u0633\u0646\u062f\u0648\u064a\u0634\u0627\u062a \u0627\u0644\u0634\u0648\u0631\u0628\u0629 \u0633\u0644\u0637\u0629 \u0645\u0642\u0628\u0644\u0627\u062a \u0635\u064a\u0646\u0649 \u0645\u0642\u0628\u0644\u0627\u062a \u0635\u064a\u0646\u0649 \u0627\u0644\u0637\u0628\u0642 \u0627\u0644\u0631\u0626\u064a\u0633\u064a \u0641\u062d\u0645 \u0627\u0644\u0637\u0628\u0642 \u0627\u0644\u0631\u0626\u064a\u0633\u064a \u0641\u062d\u0645 \u062a\u0646\u062f\u0648\u0631 \u0645\u0631\u0642 \u0627\u0644\u062e\u0636\u0627\u0631 \u0648\u0627\u0644\u0628\u0627\u0646\u064a\u064a\u0631 \u062a\u0646\u062f\u0648\u0631\u064a \u0631\u0648\u062a\u064a \u0645\u0639\u0643\u0631\u0648\u0646\u0629 \u0623\u0631\u0632 \u0645\u0642\u0644 \u0646\u0648\u062f\u0644\u0632 \u0643\u0648\u0645\u0628\u0648 \u0648 \u062b\u0627\u0644\u064a \u062e\u0627\u0635 \u0627\u0644\u0635\u062d\u0631\u0627\u0648\u064a \u062e\u0627\u0635 \u0645\u0634\u0631\u0648\u0628\u0627\u062a \u0627\u0644\u0635\u062d\u0631\u0627\u0648\u064a<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":-1,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"patiotime_single_page_hide_site_header":"","patiotime_single_page_site_header_source":"","patiotime_single_page_custom_site_header":"0","patiotime_single_page_custom_sticky_site_header":"0","patiotime_single_page_hide_page_title":"on","patiotime_single_page_header_section_size":"","patiotime_single_page_header_background_color":"","patiotime_single_page_header_background_position_x":"center","patiotime_single_page_header_background_position_y":"center","patiotime_single_page_header_background_size":"cover","patiotime_single_page_header_background_repeat":"off","patiotime_single_page_header_background_scroll":"on","patiotime_single_page_header_text_color":"","patiotime_single_page_header_show_breadcrumb":"","patiotime_single_page_site_footer_hide_main":"","patiotime_single_custom_site_footer_main_source":"","patiotime_single_custom_site_footer_main":"0","patiotime_single_page_site_footer_hide_above":"","patiotime_single_custom_site_footer_above_source":"","patiotime_single_custom_site_footer_above":"0","patiotime_single_page_site_footer_hide_instagram":"","patiotime_single_page_site_footer_hide_bottom":"","patiotime_single_custom_mobile_menu_source":"","patiotime_single_custom_mobile_menu":"0","patiotime_single_custom_mobile_menu_animation":"","patiotime_single_custom_mobile_menu_width":"","patiotime_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-8727","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/pages\/8727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/comments?post=8727"}],"version-history":[{"count":6,"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/pages\/8727\/revisions"}],"predecessor-version":[{"id":10605,"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/pages\/8727\/revisions\/10605"}],"wp:attachment":[{"href":"https:\/\/royalgulfrestaurant.com\/al_rai\/wp-json\/wp\/v2\/media?parent=8727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}